{"id":679,"count":1,"description":"","link":"https:\/\/www.thinglink.com\/blog\/tag\/experiential-marketing\/","name":"experiential marketing","slug":"experiential-marketing","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.thinglink.com\/blog\/wp-json\/wp\/v2\/tags\/679"}],"collection":[{"href":"https:\/\/www.thinglink.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.thinglink.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.thinglink.com\/blog\/wp-json\/wp\/v2\/posts?tags=679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}